{"id":1988,"date":"2022-02-17T21:34:33","date_gmt":"2022-02-17T21:34:33","guid":{"rendered":"https:\/\/dev-wp.evalartapp.com\/?post_type=ufaq&#038;p=1988"},"modified":"2022-03-23T00:36:31","modified_gmt":"2022-03-23T00:36:31","slug":"what-does-it-mean-when-a-test-is-flagged-with-fraud-risk","status":"publish","type":"ufaq","link":"https:\/\/dev-wp.evalartapp.com\/es\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/","title":{"rendered":"\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?"},"content":{"rendered":"<style>.ewd-ufaq-post-margin-symbol { border-width: 1px !important; }.ewd-ufaq-faq-title .ewd-ufaq-post-margin-symbol span { font-size: 20px !important; }div.ewd-ufaq-faq-post p { margin: 0 4cm 0 1cm !important; }div.ewd-ufaq-faq-post p {\r\n  margin: 0 0 15px !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container #ewd-ufaq-faq-list {\r\n    background-color: #ffffff;\r\n    border-radius: 16px;\r\n    border: 1px solid #E3E7ED;\r\n    padding: 0;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-div {\r\n    border: none !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-title-text h4 {\r\n    color: #222222CC;\r\n    font-size: 18px;\r\n    font-weight: 500;\r\n    line-height: 100%\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-body p {\r\n    color: #77787B;\r\n    font-size: 16px;\r\n    font-weight: 400;\r\n    line-height: 20px;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-title {\r\n    display: none;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner {\r\n    margin: 0;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner .ewd-ufaq-faq-div {\r\n    border-bottom: 1px solid #E3E7ED !important;\r\n    padding: 1.5rem !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category-inner .ewd-ufaq-faq-div:last-child {\r\n    border-bottom: none !important;\r\n}\r\n\r\n.np-pricing-ufaqs-container .ewd-ufaq-faq-category {\r\n    margin: 0px;\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='date' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/es\/wp-json\/wp\/v2\/ufaq\/1988' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-one ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-1988-rKeq1xGebG' data-post_id='1988'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\t\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p><span style=\"font-weight: 400;\">Evalart posee varios controles para detectar casos en los que un candidato podr\u00eda haber hecho trampa. Cuando una prueba est\u00e1 marcada como con posible fraude (aparece un tri\u00e1ngulo rojo en el listado de pruebas) significa que Evalart detect\u00f3 una actividad sospechosa. Esto no significa necesariamente que el candidato haya hecho trampa, pero s\u00ed que hay un riesgo mayor y por lo tanto es necesario tomar esto en cuenta para determinar si se va a considerar la prueba como v\u00e1lida.<\/span><\/p>\n<p><strong>Para ver el detalle de lo que caus\u00f3 la alerta,<\/strong><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Debe ir al reporte detallado de la prueba (haciendo clic en la lupa en el listado de pruebas enviadas o en el puntaje si se est\u00e1 viendo el reporte de resultados tabular).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ya en la vista del reporte detallado de la prueba, en la primera secci\u00f3n del reporte, en caso de un caso sospechoso, aparecer\u00e1 un texto indicando el riesgo de fraude, el nivel de riesgo y un signo de interrogaci\u00f3n. Al hacer clic en el signo de interrogaci\u00f3n aparecer\u00e1 m\u00e1s informaci\u00f3n sobre qu\u00e9 dispar\u00f3 la alerta. Por ejemplo, si se detect\u00f3 una persona distinta dando la prueba en el monitoreo web, se podr\u00e1 ver las fotos sospechosas.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En caso de detectar c\u00f3digo similar entre dos candidatos en una prueba de programaci\u00f3n, se podr\u00e1 comparar ambos c\u00f3digos para decidir si es un posible plagio.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Como se mencion\u00f3 anteriormente, es importante tener en cuenta que en ning\u00fan caso la alerta indica con 100% de certeza que el candidato hizo trampa, pero si indican un riesgo mayor comparado con una prueba que no fue marcada.\u00a0<\/span><\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A \u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude? Evalart posee varios controles para detectar casos en los que un candidato podr\u00eda haber hecho trampa. Cuando una prueba est\u00e1 marcada como con posible fraude (aparece un tri\u00e1ngulo rojo en el listado de pruebas) significa que Evalart detect\u00f3 una actividad sospechosa. Esto no [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"template":"","ufaq-category":[48],"ufaq-tag":[],"class_list":["post-1988","ufaq","type-ufaq","status-publish","hentry","ufaq-category-preguntas-frecuentes-procesos-de-seleccion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude? - Evalart<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]What does it mean when a test is flagged with fraud risk?[:es]\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?[:pb]O que significa quando um teste \u00e9 marcado como risco de fraude?[:] - Evalart\" \/>\n<meta property=\"og:description\" content=\"A \u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude? Evalart posee varios controles para detectar casos en los que un candidato podr\u00eda haber hecho trampa. Cuando una prueba est\u00e1 marcada como con posible fraude (aparece un tri\u00e1ngulo rojo en el listado de pruebas) significa que Evalart detect\u00f3 una actividad sospechosa. Esto no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/\" \/>\n<meta property=\"og:site_name\" content=\"Evalart\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-23T00:36:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/\",\"url\":\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/\",\"name\":\"[:en]What does it mean when a test is flagged with fraud risk?[:es]\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?[:pb]O que significa quando um teste \u00e9 marcado como risco de fraude?[:] - Evalart\",\"isPartOf\":{\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#website\"},\"datePublished\":\"2022-02-17T21:34:33+00:00\",\"dateModified\":\"2022-03-23T00:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev-wp.evalartapp.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\/\/dev-wp.evalartapp.com\/es\/blog\/ufaqs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"What does it mean when a test is flagged with fraud risk?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#website\",\"url\":\"https:\/\/dev-wp.evalartapp.com\/en\/\",\"name\":\"Evalart\",\"description\":\"Skills Assessment Platform for your Recruiting Process\",\"publisher\":{\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev-wp.evalartapp.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#organization\",\"name\":\"Evalart\",\"url\":\"https:\/\/dev-wp.evalartapp.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev-wp.evalartapp.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg\",\"contentUrl\":\"https:\/\/dev-wp.evalartapp.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg\",\"caption\":\"Evalart\"},\"image\":{\"@id\":\"https:\/\/dev-wp.evalartapp.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]What does it mean when a test is flagged with fraud risk?[:es]\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?[:pb]O que significa quando um teste \u00e9 marcado como risco de fraude?[:] - Evalart","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"[:en]What does it mean when a test is flagged with fraud risk?[:es]\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?[:pb]O que significa quando um teste \u00e9 marcado como risco de fraude?[:] - Evalart","og_description":"A \u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude? Evalart posee varios controles para detectar casos en los que un candidato podr\u00eda haber hecho trampa. Cuando una prueba est\u00e1 marcada como con posible fraude (aparece un tri\u00e1ngulo rojo en el listado de pruebas) significa que Evalart detect\u00f3 una actividad sospechosa. Esto no [&hellip;]","og_url":"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/","og_site_name":"Evalart","article_modified_time":"2022-03-23T00:36:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/","url":"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/","name":"[:en]What does it mean when a test is flagged with fraud risk?[:es]\u00bfQu\u00e9 significa cuando una prueba est\u00e1 marcada con riesgo de fraude?[:pb]O que significa quando um teste \u00e9 marcado como risco de fraude?[:] - Evalart","isPartOf":{"@id":"https:\/\/dev-wp.evalartapp.com\/en\/#website"},"datePublished":"2022-02-17T21:34:33+00:00","dateModified":"2022-03-23T00:36:31+00:00","breadcrumb":{"@id":"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev-wp.evalartapp.com\/en\/blog\/ufaqs\/what-does-it-mean-when-a-test-is-flagged-with-fraud-risk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev-wp.evalartapp.com\/en\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/dev-wp.evalartapp.com\/es\/blog\/ufaqs\/"},{"@type":"ListItem","position":3,"name":"What does it mean when a test is flagged with fraud risk?"}]},{"@type":"WebSite","@id":"https:\/\/dev-wp.evalartapp.com\/en\/#website","url":"https:\/\/dev-wp.evalartapp.com\/en\/","name":"Evalart","description":"Skills Assessment Platform for your Recruiting Process","publisher":{"@id":"https:\/\/dev-wp.evalartapp.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-wp.evalartapp.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dev-wp.evalartapp.com\/en\/#organization","name":"Evalart","url":"https:\/\/dev-wp.evalartapp.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev-wp.evalartapp.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev-wp.evalartapp.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","contentUrl":"https:\/\/dev-wp.evalartapp.com\/wp-content\/uploads\/2024\/03\/evalart-logo.svg","caption":"Evalart"},"image":{"@id":"https:\/\/dev-wp.evalartapp.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/ufaq\/1988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/users\/5"}],"wp:attachment":[{"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/media?parent=1988"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/ufaq-category?post=1988"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/dev-wp.evalartapp.com\/es\/wp-json\/wp\/v2\/ufaq-tag?post=1988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}